{"id":1646,"count":1,"description":"","link":"https:\/\/puckdeiboschi.noblogs.org\/nl\/tag\/leonard-peltier\/","name":"Leonard Peltier","slug":"leonard-peltier","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/puckdeiboschi.noblogs.org\/wp-json\/wp\/v2\/tags\/1646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puckdeiboschi.noblogs.org\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/puckdeiboschi.noblogs.org\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/puckdeiboschi.noblogs.org\/wp-json\/wp\/v2\/posts?tags=1646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}